{"id":2268,"date":"2023-02-03T19:20:49","date_gmt":"2023-02-03T18:20:49","guid":{"rendered":"https:\/\/uasconferences.com\/2023_icuas\/?page_id=2268"},"modified":"2023-04-12T16:02:47","modified_gmt":"2023-04-12T14:02:47","slug":"associate-editors","status":"publish","type":"page","link":"https:\/\/uasconferences.com\/2023_icuas\/associate-editors\/","title":{"rendered":"Associate editors"},"content":{"rendered":"\n<p>Adolf, Florian<br>Alexis, Kostas<br>Brandao, Alexandre Santos<br>Caballero, Fernando<br>Capello, Elisa<br>Casbeer, David<br>Chamseddine, Abbas<br>Chen, Ben M.<br>Chen, YangQuan<br>Ciarletta, Laurent<br>Coopmans, Calvin<br>de Croon, Guido<br>Doitsidis, Lefteris<br>Durand, Sylvain<br>Fasano, Giancarmine<br>Ferracuti, Francesco<br>Flores, Gerardo<br>Freddi, Alessandro<br>Fumagalli, Matteo<br>Ghadiry, Walaaeldin<br>Hasan, Agus<br>He, Chenyuan<br>Jiang, Jingjing<br>Johansen, Tor Arne<br>Kamel, Mohamed A.<br>Konert, Anna<br>Korpela, Christopher<br>Kowalczuk, Zdzislaw<br>Kulshrestha, Sanatan<br>Lee, Junsoo<br>Liu, Mushuang<br>Lovera, Marco<br>Lozano, Rogelio<br>Mancini, Adriano<br>Merino, Luis<br>Milutinovic, Dejan<br>Monteri\u00f9, Andrea<br>Morrison, James R.<br>Niu, Haoyu<br>Noura, Hassan<br>Orsag, Matko<br>Papachristos, Christos<br>Papanikolopoulos, Nikos<br>Pedda Baliyarasimhuni, Sujit<br>Pei, Hai-Long<br>Peterson, Cameron<br>Petric, Frano<br>Petrovic, Tamara<br>Ponsart, Jean-Christophe<br>Puig, Vicen\u00e7<br>Qian, Yang-Yang<br>Quagliotti, Fulvia<br>Rabbath, Camille Alain<br>Rodriguez-Cortes, Hugo<br>Romero, Hugo<br>Ruggiero, Fabio<br>Rutherford, Matthew<br>Sarcinelli-Filho, M\u00e1rio<br>Scott, Benjamyn<br>Shan, Jinjun<br>Shi, Yang<br>Shin, Hyo-Sang<br>Silano, Giuseppe<br>Simani, Silvio<br>Sousa, Joao<br>Stoica Maniu, Cristina<br>Suarez, Alejandro<br>Tahirovic, Adnan<br>Tsourdos, Antonios<br>Uchiyama, Kenji<br>Vachtsevanos, George<br>Viguria, Antidio<br>Vitzilaios, Nikolaos<br>Voos, Holger<br>Wang, Ban<br>Xu, Bin<br>Yu, Xiang<br>Yu, Ziquan<br>Zhang, Lidong<br>Zhang, Youmin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adolf, FlorianAlexis, KostasBrandao, Alexandre SantosCaballero, FernandoCapello, ElisaCasbeer, DavidChamseddine, AbbasChen, Ben M.Chen, YangQuanCiarletta, LaurentCoopmans, Calvinde Croon, GuidoDoitsidis, LefterisDurand, SylvainFasano, GiancarmineFerracuti, FrancescoFlores, GerardoFreddi, AlessandroFumagalli, MatteoGhadiry, WalaaeldinHasan, AgusHe, ChenyuanJiang, JingjingJohansen, Tor ArneKamel, Mohamed A.Konert, AnnaKorpela, ChristopherKowalczuk, ZdzislawKulshrestha, SanatanLee, JunsooLiu, MushuangLovera, MarcoLozano, RogelioMancini, AdrianoMerino, LuisMilutinovic, DejanMonteri\u00f9, AndreaMorrison, James R.Niu, HaoyuNoura, HassanOrsag, MatkoPapachristos, ChristosPapanikolopoulos, NikosPedda Baliyarasimhuni, SujitPei, Hai-LongPeterson, CameronPetric, FranoPetrovic,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/pages\/2268"}],"collection":[{"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/comments?post=2268"}],"version-history":[{"count":8,"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/pages\/2268\/revisions"}],"predecessor-version":[{"id":3118,"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/pages\/2268\/revisions\/3118"}],"wp:attachment":[{"href":"https:\/\/uasconferences.com\/2023_icuas\/wp-json\/wp\/v2\/media?parent=2268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}